{"id":28179,"date":"2024-06-11T19:01:36","date_gmt":"2024-06-11T17:01:36","guid":{"rendered":"https:\/\/teixitsmallorca.com\/?post_type=product&#038;p=28179"},"modified":"2026-07-29T13:38:47","modified_gmt":"2026-07-29T11:38:47","slug":"tela-ikat-107-escarlata","status":"publish","type":"product","link":"https:\/\/teixitsvicens.com\/es\/producto\/telas-mallorquinas\/telas-ikat\/telas-ikat-rojo\/tela-ikat-107-escarlata\/","title":{"rendered":"Tela Mallorquina ikat 107 Escarlata"},"content":{"rendered":"<p>Tela por metros artesana, elaborada con la t\u00e9cnica del ikat. Tela online para llevar a cabo tus ideas de proyectos decorativos.<\/p>\n<p>La tela Mallorquina es ideal para tapizar, para cortinas, cubrecamas, hacer tus propios cojines, y una infinidad de posibilidades creativas; adapt\u00e1ndose a todo tipo de ambientes, Mediterr\u00e1neos, r\u00fasticos, cl\u00e1sicos, modernos\u2026<\/p>\n<p>Todo esto, con un denominador com\u00fan: la calidad. Una calidad final que solamente se obtiene despu\u00e9s de muchos a\u00f1os de esfuerzo, manteniendo lo mejor de la tradici\u00f3n, utilizando los mejores materiales, las fibras naturales y los bellos colores, que dan a nuestros tejidos este car\u00e1cter tan propio.Creando entornos de agradable belleza. Para que vestir su hogar sea todo un placer.<\/p>\n<p>Decora con las telas t\u00edpicas Mallorquinas o telas de lenguas y consigue un ambiente Mediterr\u00e1neo con estos tejidos de fibras naturales.<\/p>\n<p>Telas de lino y algod\u00f3n, hechas a mano Artesanalmente en nuestro taller de Pollensa, Mallorca.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tela por metros artesana, elaborada con la t\u00e9cnica del ikat. Tela online para llevar a cabo tus ideas de proyectos&#8230;<\/p>\n","protected":false},"featured_media":28180,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[684,832,60],"product_tag":[],"class_list":["post-28179","product","type-product","status-publish","has-post-thumbnail","product_cat-telas-ikat","product_cat-telas-ikat-rojo","product_cat-telas-mallorquinas","first","instock","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tela Mallorquina ikat 107 Escarlata | Teixits Vicens<\/title>\n<meta name=\"description\" content=\"Comprar tela mallorquina ikat 107 en escarlata. 70% algod\u00f3n y 30% lino, tejida artesanalmente. Venta por metros. Ideal para cortinas y decoraci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/teixitsvicens.com\/es\/producto\/telas-mallorquinas\/telas-ikat\/telas-ikat-rojo\/tela-ikat-107-escarlata\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tela Mallorquina ikat 107 Escarlata | Teixits Vicens\" \/>\n<meta property=\"og:description\" content=\"Comprar tela mallorquina ikat 107 en escarlata. 70% algod\u00f3n y 30% lino, tejida artesanalmente. Venta por metros. Ideal para cortinas y decoraci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/teixitsvicens.com\/es\/producto\/telas-mallorquinas\/telas-ikat\/telas-ikat-rojo\/tela-ikat-107-escarlata\/\" \/>\n<meta property=\"og:site_name\" content=\"Teixits Vicens\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TeixitsVicens\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-29T11:38:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/teixitsvicens.com\/wp-content\/uploads\/2024\/06\/TELESV-0313.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tela Mallorquina ikat 107 Escarlata | Teixits Vicens","description":"Comprar tela mallorquina ikat 107 en escarlata. 70% algod\u00f3n y 30% lino, tejida artesanalmente. Venta por metros. Ideal para cortinas y decoraci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/teixitsvicens.com\/es\/producto\/telas-mallorquinas\/telas-ikat\/telas-ikat-rojo\/tela-ikat-107-escarlata\/","og_locale":"es_ES","og_type":"article","og_title":"Tela Mallorquina ikat 107 Escarlata | Teixits Vicens","og_description":"Comprar tela mallorquina ikat 107 en escarlata. 70% algod\u00f3n y 30% lino, tejida artesanalmente. Venta por metros. Ideal para cortinas y decoraci\u00f3n.","og_url":"https:\/\/teixitsvicens.com\/es\/producto\/telas-mallorquinas\/telas-ikat\/telas-ikat-rojo\/tela-ikat-107-escarlata\/","og_site_name":"Teixits Vicens","article_publisher":"https:\/\/www.facebook.com\/TeixitsVicens\/","article_modified_time":"2026-07-29T11:38:47+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/teixitsvicens.com\/wp-content\/uploads\/2024\/06\/TELESV-0313.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/teixitsvicens.com\/es\/producto\/telas-mallorquinas\/telas-ikat\/telas-ikat-rojo\/tela-ikat-107-escarlata\/","url":"https:\/\/teixitsvicens.com\/es\/producto\/telas-mallorquinas\/telas-ikat\/telas-ikat-rojo\/tela-ikat-107-escarlata\/","name":"Tela Mallorquina ikat 107 Escarlata | Teixits Vicens","isPartOf":{"@id":"https:\/\/teixitsvicens.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/teixitsvicens.com\/es\/producto\/telas-mallorquinas\/telas-ikat\/telas-ikat-rojo\/tela-ikat-107-escarlata\/#primaryimage"},"image":{"@id":"https:\/\/teixitsvicens.com\/es\/producto\/telas-mallorquinas\/telas-ikat\/telas-ikat-rojo\/tela-ikat-107-escarlata\/#primaryimage"},"thumbnailUrl":"https:\/\/teixitsvicens.com\/wp-content\/uploads\/2024\/06\/TELESV-0313.jpg","datePublished":"2024-06-11T17:01:36+00:00","dateModified":"2026-07-29T11:38:47+00:00","description":"Comprar tela mallorquina ikat 107 en escarlata. 70% algod\u00f3n y 30% lino, tejida artesanalmente. Venta por metros. Ideal para cortinas y decoraci\u00f3n.","breadcrumb":{"@id":"https:\/\/teixitsvicens.com\/es\/producto\/telas-mallorquinas\/telas-ikat\/telas-ikat-rojo\/tela-ikat-107-escarlata\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/teixitsvicens.com\/es\/producto\/telas-mallorquinas\/telas-ikat\/telas-ikat-rojo\/tela-ikat-107-escarlata\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/teixitsvicens.com\/es\/producto\/telas-mallorquinas\/telas-ikat\/telas-ikat-rojo\/tela-ikat-107-escarlata\/#primaryimage","url":"https:\/\/teixitsvicens.com\/wp-content\/uploads\/2024\/06\/TELESV-0313.jpg","contentUrl":"https:\/\/teixitsvicens.com\/wp-content\/uploads\/2024\/06\/TELESV-0313.jpg","width":1200,"height":800,"caption":"Muestra de tejido artesanal modelo 313 de Teixits Vicens"},{"@type":"BreadcrumbList","@id":"https:\/\/teixitsvicens.com\/es\/producto\/telas-mallorquinas\/telas-ikat\/telas-ikat-rojo\/tela-ikat-107-escarlata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/teixitsvicens.com\/es\/home\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/teixitsvicens.com\/es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Tela Mallorquina ikat 107 Escarlata"}]},{"@type":"WebSite","@id":"https:\/\/teixitsvicens.com\/es\/#website","url":"https:\/\/teixitsvicens.com\/es\/","name":"Teixits Vicens","description":"Taller textil artesano","publisher":{"@id":"https:\/\/teixitsvicens.com\/es\/#organization"},"alternateName":"Teixits Vicens","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/teixitsvicens.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/teixitsvicens.com\/es\/#organization","name":"Teixits Vicens","url":"https:\/\/teixitsvicens.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/teixitsvicens.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/teixitsvicens.com\/wp-content\/uploads\/2025\/10\/logo-teixits-vicents.png","contentUrl":"https:\/\/teixitsvicens.com\/wp-content\/uploads\/2025\/10\/logo-teixits-vicents.png","width":629,"height":131,"caption":"Teixits Vicens"},"image":{"@id":"https:\/\/teixitsvicens.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TeixitsVicens\/","https:\/\/www.instagram.com\/teixitsvicens\/"]}]}},"_links":{"self":[{"href":"https:\/\/teixitsvicens.com\/es\/wp-json\/wp\/v2\/product\/28179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teixitsvicens.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/teixitsvicens.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/teixitsvicens.com\/es\/wp-json\/wp\/v2\/comments?post=28179"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teixitsvicens.com\/es\/wp-json\/wp\/v2\/media\/28180"}],"wp:attachment":[{"href":"https:\/\/teixitsvicens.com\/es\/wp-json\/wp\/v2\/media?parent=28179"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/teixitsvicens.com\/es\/wp-json\/wp\/v2\/product_brand?post=28179"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/teixitsvicens.com\/es\/wp-json\/wp\/v2\/product_cat?post=28179"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/teixitsvicens.com\/es\/wp-json\/wp\/v2\/product_tag?post=28179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}